{"id":24522,"date":"2024-03-05T08:50:11","date_gmt":"2024-03-05T08:50:11","guid":{"rendered":"https:\/\/lahehouse.com\/?page_id=24522"},"modified":"2024-03-22T09:11:04","modified_gmt":"2024-03-22T09:11:04","slug":"drivhus-ml-1","status":"publish","type":"page","link":"https:\/\/lahehouse.com\/da\/produkter\/drivhus-ml-1\/","title":{"rendered":"Drivhus ML 1"},"content":{"rendered":"\n  <div class=\"banner has-hover is-full-height\" id=\"banner-703189160\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"2500\" height=\"1667\" src=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2024\/03\/Drivhus-ml-1.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1029149916\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y80 lg-y80 res-text\">\n                     <div data-animate=\"none\">           <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\t<div id=\"text-2921072487\" class=\"text\">\n\t\t\n<h1>DRIVHUS ML 1<\/h1>\n<h3>1,95 x 2,85 m \/ 5,55 m2<\/h3>\n\t\t\n<style>\n#text-2921072487 {\n  font-size: 0.75rem;\n  text-align: center;\n}\n@media (min-width:550px) {\n  #text-2921072487 {\n    font-size: 1.2rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-280735104\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-280735104 {\n  padding-top: 75px;\n}\n@media (min-width:550px) {\n  #gap-280735104 {\n    padding-top: 30px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"https:\/\/lahehouse.com\/da\/forhandlere\/\" class=\"button white is-outline is-large reveal-icon\" style=\"border-radius:99px;\">\n\t\t<span>Forhandlere<\/span>\n\t<i class=\"icon-play\" aria-hidden=\"true\"><\/i><\/a>\n\n<a href=\"#teknisk\" class=\"button white is-outline is-large reveal-icon\" style=\"border-radius:99px;\">\n\t\t<span>Teknisk info<\/span>\n\t<i class=\"icon-play\" aria-hidden=\"true\"><\/i><\/a>\n\n              <\/div>\n           <\/div>\n       <\/div>                     \n<style>\n#text-box-1029149916 {\n  width: 80%;\n}\n#text-box-1029149916 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-1029149916 {\n    width: 100%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-703189160 {\n  padding-top: 100%;\n}\n#banner-703189160 .overlay {\n  background-color: rgba(0, 0, 0, 0.4);\n}\n#banner-703189160 .banner-bg img {\n  object-position: 50% 80%;\n}\n@media (min-width:550px) {\n  #banner-703189160 {\n    padding-top: 100%;\n  }\n  #banner-703189160 .overlay {\n    background-color: rgba(0, 0, 0, 0.3);\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n\t<section class=\"section\" id=\"section_265963071\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row align-middle align-right\" style=\"max-width:1200px\" id=\"row-1421959314\">\n\n\t<div id=\"col-50067096\" class=\"col medium-12 small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"gap-525570560\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-525570560 {\n  padding-top: 5px;\n}\n@media (min-width:550px) {\n  #gap-525570560 {\n    padding-top: 50px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-636447955\" class=\"text\">\n\t\t\n<h5>LUKSURI\u00d8ST OG ELEGANT<\/h5>\n<div id=\"text-1647802272\" class=\"text\">\n<h2>Drivhus ML 1<\/h2>\n<\/div>\n\t\t\n<style>\n#text-636447955 {\n  font-size: 1.75rem;\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3200652763\" class=\"text\">\n\t\t\n<p>L\u00e4he drivhus Mini er et attraktivt og h\u00f8jkvalitets tr\u00e6drivhus lavet af slidst\u00e6rkt og st\u00e6rkt varmebehandlet tr\u00e6 og 4 mm h\u00e6rdet glas. Ved et L\u00e4he drivhus i tr\u00e6 hviler tr\u00e6rammen p\u00e5 et st\u00e6rkt fundament og glasset n\u00e5r til jorden, hvilket sikrer maksimal plads og lys i drivhuset. Drivhuset f\u00e5s i en lang r\u00e6kke af olier eller farver, hvorfra alle kan finde en passende. Drivhus i tr\u00e6 Mini er ideel til dyrkning af gr\u00f8ntsager, krydderier og blomster.<\/p>\n\t\t\n<style>\n#text-3200652763 {\n  font-size: 1.2rem;\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-50067096 > .col-inner {\n  padding: 10px 30px 0px 30px;\n}\n@media (min-width:550px) {\n  #col-50067096 > .col-inner {\n    padding: 0 50px 20px 50px;\n  }\n}\n@media (min-width:850px) {\n  #col-50067096 > .col-inner {\n    padding: 50px 50px 50px 50px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_265963071 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  min-height: 600px;\n  background-color: rgb(210, 210, 210);\n}\n<\/style>\n\t<\/section>\n\t\n\n  <div class=\"banner has-hover\" id=\"banner-1994519167\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1940\" src=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2024\/03\/Drivhus-ml-1-3.png\" class=\"bg attachment-original size-original\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1291863615\" class=\"text-box banner-layer x90 md-x90 lg-x90 y95 md-y90 lg-y90 res-text\">\n                                <div class=\"text-box-content text \">\n              \n              <div class=\"text-inner text-center\">\n                  \n<a href=\"https:\/\/lahehouse.com\/da\/galleri\/\" class=\"button primary is-outline is-large reveal-icon\" style=\"border-radius:99px;\">\n\t\t<span>Galleri<\/span>\n\t<i class=\"icon-play\" aria-hidden=\"true\"><\/i><\/a>\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1291863615 {\n  width: 40%;\n}\n#text-box-1291863615 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n   <div id=\"text-box-1041838195\" class=\"text-box banner-layer hide-for-medium x5 md-x5 lg-x5 y95 md-y45 lg-y45 res-text\">\n                                <div class=\"text-box-content text \">\n              \n              <div class=\"text-inner text-center\">\n                  \n\t<div id=\"text-4091409812\" class=\"text\">\n\t\t\n<p>UNIKT OG PATENTERET DESIGN<\/p>\n\t\t\n<style>\n#text-4091409812 {\n  font-size: 2rem;\n}\n<\/style>\n\t<\/div>\n\t\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1041838195 {\n  width: 50%;\n}\n#text-box-1041838195 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n              <div class=\"height-fix is-invisible\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1940\" src=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2024\/03\/Drivhus-ml-1-3.png\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2024\/03\/Drivhus-ml-1-3.png 1920w, https:\/\/lahehouse.com\/wp-content\/uploads\/2024\/03\/Drivhus-ml-1-3-396x400.png 396w, https:\/\/lahehouse.com\/wp-content\/uploads\/2024\/03\/Drivhus-ml-1-3-792x800.png 792w, https:\/\/lahehouse.com\/wp-content\/uploads\/2024\/03\/Drivhus-ml-1-3-768x776.png 768w, https:\/\/lahehouse.com\/wp-content\/uploads\/2024\/03\/Drivhus-ml-1-3-1520x1536.png 1520w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/div>\n            \n<style>\n#banner-1994519167 .overlay {\n  background-color: rgba(0, 0, 0, 0.3);\n}\n#banner-1994519167 {\n  background-color: rgb(210, 210, 210);\n}\n#banner-1994519167 .banner-bg img {\n  object-position: 50% 0%;\n}\n<\/style>\n  <\/div>\n\n\n\n\t<section class=\"section\" id=\"section_1983510847\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\" style=\"max-width:1200px\" id=\"row-599312607\">\n\n\t<div id=\"col-542521441\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2960354972\" class=\"text\">\n\t\t\n<h5>STILTIGT OG PRAKTISK<\/h5>\n<h2>Drivhus i tr\u00e6 er centrum i din have<\/h2>\n\t\t\n<style>\n#text-2960354972 {\n  font-size: 1.75rem;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3241484355\" class=\"text\">\n\t\t\n<div id=\"text-1116106504\" class=\"text\">Et h\u00f8jkvalitets varmebehandlet tr\u00e6 drivhus med eksklusive farver og moderne materialer giver din have et luksuri\u00f8st udtryk. Dens st\u00e6rke og holdbare ramme g\u00f8r det til en investering, der vil vare hele livet, hvis den vedligeholdes ordentligt. L\u00e4he stilfulde og praktiske drivhus i tr\u00e6 pryder hver g\u00e5rd. Drivhus med tr\u00e6ramme ser klassisk godt ud og er omdrejningspunktet i enhver have. Det passer godt sammen med resten af haveanl\u00e6gget og er \u00e6stetisk tiltalende.<\/div>\n\t\t\n<style>\n#text-3241484355 {\n  font-size: 1.2rem;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-542521441 > .col-inner {\n  padding: 0px 0px 0px px;\n}\n@media (min-width:550px) {\n  #col-542521441 > .col-inner {\n    padding: 50px 50px 50px 50px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1983510847 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  min-height: 600px;\n  background-color: rgb(210, 210, 210);\n}\n@media (min-width:550px) {\n  #section_1983510847 {\n    padding-top: 0px;\n    padding-bottom: 0px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\n  <div class=\"banner has-hover is-full-height\" id=\"banner-512662164\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"2500\" height=\"1667\" src=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2024\/03\/Drivhus-ml-1-2.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1665050669\" class=\"text-box banner-layer x50 md-x50 lg-x50 y80 md-y80 lg-y80 res-text\">\n                                <div class=\"text-box-content text \">\n              \n              <div class=\"text-inner text-center\">\n                  \n<div class=\"row row-small align-equal align-center\"  id=\"row-1775910242\">\n\n\t<div id=\"col-1801867521\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgba(255, 255, 255, 0.9);\" >\n\t\t\t\n\t\t\t\n<h4><strong>VARMEBEHANDLET TR\u00c6<\/strong><\/h4>\n<p>Drivhus ML 1 er lavet af varmebehandlet skandinavisk fyr.<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1801867521 > .col-inner {\n  border-radius: 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1606763512\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgba(255, 255, 255, 0.9);\" >\n\t\t\t\n\t\t\t\n<h4><strong>PATENTERET DESIGN<\/strong><\/h4>\n<p>Drivhus ML 1 har EUIPO designpatent anmeldt.<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1606763512 > .col-inner {\n  border-radius: 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1159866270\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgba(255, 255, 255, 0.9);\" >\n\t\t\t\n\t\t\t\n<h4><strong>GARANTI 10 \u00c5R<\/strong><\/h4>\n<p>Drivhus ML 1 har 10 \u00e5rs garanti p\u00e5 tr\u00e6ramme.<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1159866270 > .col-inner {\n  border-radius: 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-313495952\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgba(255, 255, 255, 0.9);\" >\n\t\t\t\n\t\t\t\n<h4><strong>H\u00c6RDET SIKKERHEDSGLAS<\/strong><\/h4>\n<p>Drivhus ML 1 er lavet af 4 mm h\u00e6rdet sikkerhedsglas.<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-313495952 > .col-inner {\n  border-radius: 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1552246539\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgba(255, 255, 255, 0.9);\" >\n\t\t\t\n\t\t\t\n<h4><strong>LANG LIVSCYKLUS<\/strong><\/h4>\n<p>Drivhus ML 1 forventede livscyklus er op til 50 \u00e5r.<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1552246539 > .col-inner {\n  border-radius: 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1599281933\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgba(255, 255, 255, 0.9);\" >\n\t\t\t\n\t\t\t\n<h4><strong>H\u00d8J KVALITET EKSTRA<\/strong><\/h4>\n<p>Drivhus ML 1 har kvalitetsd\u00f8rl\u00e5s og automatisk vindues\u00e5bner medf\u00f8lger.<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1599281933 > .col-inner {\n  border-radius: 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-1775910242 > .col > .col-inner {\n  padding: 10px 10px 10px 10px;\n}\n<\/style>\n<\/div>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1665050669 {\n  width: 90%;\n}\n#text-box-1665050669 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-1665050669 {\n    width: 90%;\n  }\n}\n@media (min-width:850px) {\n  #text-box-1665050669 {\n    width: 90%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-512662164 {\n  padding-top: 600px;\n}\n#banner-512662164 .overlay {\n  background-color: rgba(0, 0, 0, 0.3);\n}\n#banner-512662164 .banner-bg img {\n  object-position: 50% 80%;\n}\n@media (min-width:550px) {\n  #banner-512662164 {\n    padding-top: 100%;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n\t<section class=\"section\" id=\"section_1120265126\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\" style=\"max-width:1200px\" id=\"row-694272454\">\n\n\t<div id=\"col-709626969\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-315094586\" class=\"text\">\n\t\t\n<h5>MODERNE MATERIALER<\/h5>\n<h2>Lang levetid og 10 \u00e5rs garanti<\/h2>\n\t\t\n<style>\n#text-315094586 {\n  font-size: 1.75rem;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1612358233\" class=\"text\">\n\t\t\n<div id=\"text-1116106504\" class=\"text\">L\u00e4he drivhus i tr\u00e6 ML 1 er blevet dygtigt fremstillet af specialister med h\u00f8j kvalitet og holdbare materialer. Vi bruger kun naturlige og moderne materialer i produktionen af drivhuset, og det er specielt udviklet med nordiske vejrforhold i tankerne. Som f\u00f8lge heraf kommer drivhusets tr\u00e6konstruktion med 10 \u00e5rs garanti og forventet levetid p\u00e5 50 \u00e5r.<\/div>\n\t\t\n<style>\n#text-1612358233 {\n  font-size: 1.2rem;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-1789668823\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1789668823 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"https:\/\/lahehouse.com\/da\/yderligere-information\/\" class=\"button primary is-outline is-large reveal-icon\" style=\"border-radius:99px;\">\n\t\t<span>Les mer<\/span>\n\t<i class=\"icon-play\" aria-hidden=\"true\"><\/i><\/a>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-709626969 > .col-inner {\n  padding: 0px 0px 0px px;\n}\n@media (min-width:550px) {\n  #col-709626969 > .col-inner {\n    padding: 50px 50px 50px 50px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1120265126 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  min-height: 600px;\n  background-color: rgb(210, 210, 210);\n}\n@media (min-width:550px) {\n  #section_1120265126 {\n    padding-top: 0px;\n    padding-bottom: 0px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\n  <div class=\"banner has-hover is-full-height\" id=\"banner-1065665511\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2024\/03\/Drivhus-ml-1-4.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1065665511 {\n  padding-top: 100%;\n}\n#banner-1065665511 .overlay {\n  background-color: rgba(0, 0, 0, 0.3);\n}\n#banner-1065665511 .banner-bg img {\n  object-position: 50% 80%;\n}\n@media (min-width:550px) {\n  #banner-1065665511 {\n    padding-top: 100%;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n\t<section class=\"section\" id=\"section_33914788\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\" style=\"max-width:1200px\" id=\"row-827401841\">\n\n\t<div id=\"col-131498280\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2276065197\" class=\"text\">\n\t\t\n<h5>B\u00c6REDYGTIG FREMTID<\/h5>\n<h2>Lille CO2-fodaftryk<\/h2>\n\t\t\n<style>\n#text-2276065197 {\n  font-size: 1.75rem;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-273327209\" class=\"text\">\n\t\t\n<div id=\"text-1116106504\" class=\"text\">En gr\u00f8n og ren fremtid er meget vigtig for os. Ved at kombinere vedvarende materialer (tr\u00e6 og glas), h\u00e5ndv\u00e6rk og moderne teknologier, h\u00e5ber vi at opn\u00e5 det mindst mulige CO2-fodaftryk. Vores tr\u00e6drivhuses naturlige materialer og lange livscyklus bidrager til dette m\u00e5l.<\/div>\n\t\t\n<style>\n#text-273327209 {\n  font-size: 1.2rem;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-931431768\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-931431768 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"https:\/\/lahehouse.com\/da\/baeredygtighed\/\" class=\"button primary is-outline is-large reveal-icon\" style=\"border-radius:99px;\">\n\t\t<span>Les mer<\/span>\n\t<i class=\"icon-play\" aria-hidden=\"true\"><\/i><\/a>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-131498280 > .col-inner {\n  padding: 0px 0px 0px px;\n}\n@media (min-width:550px) {\n  #col-131498280 > .col-inner {\n    padding: 50px 50px 50px 50px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_33914788 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  min-height: 600px;\n  background-color: rgb(210, 210, 210);\n}\n@media (min-width:550px) {\n  #section_33914788 {\n    padding-top: 0px;\n    padding-bottom: 0px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\n  <div class=\"banner has-hover is-full-height\" id=\"banner-1840678980\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"2500\" height=\"1667\" src=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2024\/03\/Drivhus-ml-1-2.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1840678980 {\n  padding-top: 100%;\n}\n#banner-1840678980 .overlay {\n  background-color: rgba(0, 0, 0, 0.3);\n}\n#banner-1840678980 .banner-bg img {\n  object-position: 50% 80%;\n}\n@media (min-width:550px) {\n  #banner-1840678980 {\n    padding-top: 100%;\n  }\n}\n<\/style>\n  <\/div>\n\n\n<span class=\"scroll-to\" data-label=\"Scroll to: #teknisk\" data-bullet=\"false\" data-link=\"#teknisk\" data-title=\"Teknisk\"><a name=\"teknisk\"><\/a><\/span>\n\n\t<section class=\"section\" id=\"section_928069386\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row align-middle align-center\" style=\"max-width:1200px\" id=\"row-374133562\">\n\n\t<div id=\"col-1020329042\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-1252931909\" class=\"text\">\n\t\t\n<h2>Teknisk information<\/h2>\n\t\t\n<style>\n#text-1252931909 {\n  font-size: 1.75rem;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-24376242\" class=\"col medium-12 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left is-large\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 25px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol-400x400.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol-400x400.png 400w, https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol-280x280.png 280w, https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol-300x300.png 300w, https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol-100x100.png 100w, https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol.png 512w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<h3>Produktblad<\/h3>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left is-large\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 25px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol-400x400.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol-400x400.png 400w, https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol-280x280.png 280w, https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol-300x300.png 300w, https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol-100x100.png 100w, https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol.png 512w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<h3>Farvekort<\/h3>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left is-large\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 25px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol-400x400.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol-400x400.png 400w, https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol-280x280.png 280w, https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol-300x300.png 300w, https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol-100x100.png 100w, https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol.png 512w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<h3>Fundamenttegninger<\/h3>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left is-large\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 25px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol-400x400.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol-400x400.png 400w, https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol-280x280.png 280w, https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol-300x300.png 300w, https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol-100x100.png 100w, https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol.png 512w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<h3><a href=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2024\/03\/Installation-manual-ML1.pdf\" target=\"_blank\" rel=\"noopener\">Installationsmanual<\/a><\/h3>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left is-large\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 25px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol-400x400.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol-400x400.png 400w, https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol-280x280.png 280w, https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol-300x300.png 300w, https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol-100x100.png 100w, https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol.png 512w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<h3>3D model<\/h3>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left is-large\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 25px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol-400x400.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol-400x400.png 400w, https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol-280x280.png 280w, https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol-300x300.png 300w, https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol-100x100.png 100w, https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol.png 512w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<h3>Garantibetingelser<\/h3>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left is-large\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 25px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol-400x400.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol-400x400.png 400w, https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol-280x280.png 280w, https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol-300x300.png 300w, https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol-100x100.png 100w, https:\/\/lahehouse.com\/wp-content\/uploads\/2021\/10\/Download-symbol.png 512w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<h3>Vedligeholdelse<\/h3>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-24376242 > .col-inner {\n  padding: 10px 30px 0px 30px;\n}\n@media (min-width:550px) {\n  #col-24376242 > .col-inner {\n    padding: 0 50px 20px 50px;\n  }\n}\n@media (min-width:850px) {\n  #col-24376242 > .col-inner {\n    padding: 0px 0px 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1199825783\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n        <div class=\"modelViewerBlock\" data-attributes='{&quot;align&quot;:&quot;center&quot;,&quot;uniqueId&quot;:&quot;model24273&quot;,&quot;currentViewer&quot;:&quot;modelViewer&quot;,&quot;multiple&quot;:false,&quot;O3DVSettings&quot;:{&quot;isFullscreen&quot;:true,&quot;isPagination&quot;:false,&quot;isNavigation&quot;:false,&quot;camera&quot;:null,&quot;mouseControl&quot;:true},&quot;environmentImage&quot;:null,&quot;lazyLoad&quot;:false,&quot;loading&quot;:&quot;auto&quot;,&quot;autoplay&quot;:false,&quot;shadow&quot;:&quot;1&quot;,&quot;autoRotate&quot;:true,&quot;zoomLevel&quot;:null,&quot;zoom&quot;:false,&quot;isPagination&quot;:false,&quot;isNavigation&quot;:false,&quot;hotspotStyle&quot;:&quot;style-1&quot;,&quot;preload&quot;:&quot;auto&quot;,&quot;rotationPerSecond&quot;:&quot;30&quot;,&quot;mouseControl&quot;:true,&quot;lockXAxisRotation&quot;:false,&quot;lockYAxisRotation&quot;:false,&quot;fullscreen&quot;:true,&quot;zoomInOutBtn&quot;:false,&quot;cameraBtn&quot;:false,&quot;variant&quot;:false,&quot;loadingPercentage&quot;:false,&quot;progressBar&quot;:true,&quot;rotate&quot;:false,&quot;rotateDelay&quot;:3000,&quot;rotateAlongX&quot;:&quot;0&quot;,&quot;rotateAlongY&quot;:&quot;75&quot;,&quot;exposure&quot;:&quot;1&quot;,&quot;stylesheet&quot;:null,&quot;additional&quot;:{&quot;ID&quot;:&quot;&quot;,&quot;Class&quot;:&quot;&quot;,&quot;CSS&quot;:null},&quot;animation&quot;:false,&quot;woo&quot;:false,&quot;selectedAnimation&quot;:&quot;&quot;,&quot;placement&quot;:&quot;shortcode&quot;,&quot;styles&quot;:{&quot;width&quot;:&quot;100%&quot;,&quot;height&quot;:&quot;400px&quot;,&quot;bgColor&quot;:&quot;#d2d2d2&quot;,&quot;progressBarColor&quot;:null},&quot;model&quot;:{&quot;modelUrl&quot;:&quot;https:\\\/\\\/lahehouse.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Greenhouse-ml-1.glb&quot;,&quot;poster&quot;:&quot;&quot;,&quot;skyboxImage&quot;:null,&quot;arEnabled&quot;:false,&quot;arMode&quot;:&quot;webxr scene-viewer quick-look&quot;,&quot;arPlacement&quot;:&quot;floor&quot;,&quot;modelISOSrc&quot;:null,&quot;initialView&quot;:[],&quot;hotspots&quot;:[]},&quot;models&quot;:[]}'><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-705199707\" class=\"col medium-12 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left is-large\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 25px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2022\/11\/Measure.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2022\/11\/Measure.png 200w, https:\/\/lahehouse.com\/wp-content\/uploads\/2022\/11\/Measure-100x100.png 100w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<h3>L\u00e6ngde \u2013 285 cm<\/h3>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left is-large\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 25px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2022\/11\/Measure.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2022\/11\/Measure.png 200w, https:\/\/lahehouse.com\/wp-content\/uploads\/2022\/11\/Measure-100x100.png 100w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<h3>Bredde \u2013 195 cm<\/h3>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left is-large\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 25px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2022\/11\/Measure.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2022\/11\/Measure.png 200w, https:\/\/lahehouse.com\/wp-content\/uploads\/2022\/11\/Measure-100x100.png 100w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<h3>Rygh\u00f8jde \u2013 235 cm<\/h3>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left is-large\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 25px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2022\/11\/Measure.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2022\/11\/Measure.png 200w, https:\/\/lahehouse.com\/wp-content\/uploads\/2022\/11\/Measure-100x100.png 100w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<h3>Sideh\u00f8jde \u2013 156 cm<\/h3>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left is-large\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 25px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2022\/11\/Measure.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2022\/11\/Measure.png 200w, https:\/\/lahehouse.com\/wp-content\/uploads\/2022\/11\/Measure-100x100.png 100w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<h3>D\u00f8rh\u00f8jde \u2013 180 cm<\/h3>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left is-large\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 25px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2022\/11\/Measure.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2022\/11\/Measure.png 200w, https:\/\/lahehouse.com\/wp-content\/uploads\/2022\/11\/Measure-100x100.png 100w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<h3>D\u00f8rbredde \u2013 65 cm<\/h3>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left is-large\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 25px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2022\/11\/Measure.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2022\/11\/Measure.png 200w, https:\/\/lahehouse.com\/wp-content\/uploads\/2022\/11\/Measure-100x100.png 100w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<h3>Tagh\u00e6ldning \u2013 36\u00b0<\/h3>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-705199707 > .col-inner {\n  padding: 10px 30px 0px 30px;\n}\n@media (min-width:550px) {\n  #col-705199707 > .col-inner {\n    padding: 0 50px 20px 50px;\n  }\n}\n@media (min-width:850px) {\n  #col-705199707 > .col-inner {\n    padding: 0px 0px 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_928069386 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  min-height: 600px;\n  background-color: rgb(210, 210, 210);\n}\n<\/style>\n\t<\/section>\n\t\n\n  <div class=\"banner has-hover is-full-height\" id=\"banner-484024471\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2023\/01\/Produkter.jpeg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1979457125\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\t<div id=\"text-3824926834\" class=\"text\">\n\t\t\n<div id=\"text-264448993\" class=\"text\">\n<h2>Opdag andre drivhuse i vores udvalg<\/h2>\n<\/div>\n\t\t\n<style>\n#text-3824926834 {\n  font-size: 1rem;\n}\n@media (min-width:550px) {\n  #text-3824926834 {\n    font-size: 1.4rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-1609579732\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1609579732 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"https:\/\/lahehouse.com\/da\/produkter\/\" class=\"button white is-outline is-large reveal-icon\" style=\"border-radius:99px;\">\n\t\t<span>Produkter<\/span>\n\t<i class=\"icon-play\" aria-hidden=\"true\"><\/i><\/a>\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1979457125 {\n  width: 80%;\n}\n#text-box-1979457125 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-1979457125 {\n    width: 60%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-484024471 {\n  padding-top: 100%;\n}\n#banner-484024471 .overlay {\n  background-color: rgba(0, 0, 0, 0.3);\n}\n#banner-484024471 .banner-bg img {\n  object-position: 64% 69%;\n}\n@media (min-width:550px) {\n  #banner-484024471 {\n    padding-top: 100%;\n  }\n  #banner-484024471 .overlay {\n    background-color: rgba(0, 0, 0, 0.3);\n  }\n}\n<\/style>\n  <\/div>\n\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":24524,"parent":6487,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-transparent-header-light.php","meta":{"footnotes":""},"class_list":["post-24522","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Drivhus ML 1 - L\u00e4he House<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lahehouse.com\/da\/produkter\/drivhus-ml-1\/\" \/>\n<meta property=\"og:locale\" content=\"da_DK\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Drivhus ML 1 - L\u00e4he House\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lahehouse.com\/da\/produkter\/drivhus-ml-1\/\" \/>\n<meta property=\"og:site_name\" content=\"L\u00e4he House\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-22T09:11:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lahehouse.com\/wp-content\/uploads\/2024\/03\/Drivhus-ml-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimeret l\u00e6setid\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutter\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lahehouse.com\\\/da\\\/produkter\\\/drivhus-ml-1\\\/\",\"url\":\"https:\\\/\\\/lahehouse.com\\\/da\\\/produkter\\\/drivhus-ml-1\\\/\",\"name\":\"Drivhus ML 1 - L\u00e4he House\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lahehouse.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lahehouse.com\\\/da\\\/produkter\\\/drivhus-ml-1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lahehouse.com\\\/da\\\/produkter\\\/drivhus-ml-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lahehouse.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Drivhus-ml-1.jpg\",\"datePublished\":\"2024-03-05T08:50:11+00:00\",\"dateModified\":\"2024-03-22T09:11:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lahehouse.com\\\/da\\\/produkter\\\/drivhus-ml-1\\\/#breadcrumb\"},\"inLanguage\":\"da-DK\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lahehouse.com\\\/da\\\/produkter\\\/drivhus-ml-1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"da-DK\",\"@id\":\"https:\\\/\\\/lahehouse.com\\\/da\\\/produkter\\\/drivhus-ml-1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lahehouse.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Drivhus-ml-1.jpg\",\"contentUrl\":\"https:\\\/\\\/lahehouse.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Drivhus-ml-1.jpg\",\"width\":2500,\"height\":1667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lahehouse.com\\\/da\\\/produkter\\\/drivhus-ml-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lahehouse.com\\\/da\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produkter\",\"item\":\"https:\\\/\\\/lahehouse.com\\\/da\\\/produkter\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Drivhus ML 1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lahehouse.com\\\/#website\",\"url\":\"https:\\\/\\\/lahehouse.com\\\/\",\"name\":\"L\u00e4he House\",\"description\":\"Wooden greenhouses\",\"publisher\":{\"@id\":\"https:\\\/\\\/lahehouse.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lahehouse.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"da-DK\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lahehouse.com\\\/#organization\",\"name\":\"L\u00e4he House\",\"url\":\"https:\\\/\\\/lahehouse.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"da-DK\",\"@id\":\"https:\\\/\\\/lahehouse.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lahehouse.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Greenhouses-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/lahehouse.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Greenhouses-1.jpeg\",\"width\":1920,\"height\":1080,\"caption\":\"L\u00e4he House\"},\"image\":{\"@id\":\"https:\\\/\\\/lahehouse.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Drivhus ML 1 - L\u00e4he House","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lahehouse.com\/da\/produkter\/drivhus-ml-1\/","og_locale":"da_DK","og_type":"article","og_title":"Drivhus ML 1 - L\u00e4he House","og_url":"https:\/\/lahehouse.com\/da\/produkter\/drivhus-ml-1\/","og_site_name":"L\u00e4he House","article_modified_time":"2024-03-22T09:11:04+00:00","og_image":[{"width":2500,"height":1667,"url":"https:\/\/lahehouse.com\/wp-content\/uploads\/2024\/03\/Drivhus-ml-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimeret l\u00e6setid":"5 minutter"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lahehouse.com\/da\/produkter\/drivhus-ml-1\/","url":"https:\/\/lahehouse.com\/da\/produkter\/drivhus-ml-1\/","name":"Drivhus ML 1 - L\u00e4he House","isPartOf":{"@id":"https:\/\/lahehouse.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lahehouse.com\/da\/produkter\/drivhus-ml-1\/#primaryimage"},"image":{"@id":"https:\/\/lahehouse.com\/da\/produkter\/drivhus-ml-1\/#primaryimage"},"thumbnailUrl":"https:\/\/lahehouse.com\/wp-content\/uploads\/2024\/03\/Drivhus-ml-1.jpg","datePublished":"2024-03-05T08:50:11+00:00","dateModified":"2024-03-22T09:11:04+00:00","breadcrumb":{"@id":"https:\/\/lahehouse.com\/da\/produkter\/drivhus-ml-1\/#breadcrumb"},"inLanguage":"da-DK","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lahehouse.com\/da\/produkter\/drivhus-ml-1\/"]}]},{"@type":"ImageObject","inLanguage":"da-DK","@id":"https:\/\/lahehouse.com\/da\/produkter\/drivhus-ml-1\/#primaryimage","url":"https:\/\/lahehouse.com\/wp-content\/uploads\/2024\/03\/Drivhus-ml-1.jpg","contentUrl":"https:\/\/lahehouse.com\/wp-content\/uploads\/2024\/03\/Drivhus-ml-1.jpg","width":2500,"height":1667},{"@type":"BreadcrumbList","@id":"https:\/\/lahehouse.com\/da\/produkter\/drivhus-ml-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lahehouse.com\/da\/"},{"@type":"ListItem","position":2,"name":"Produkter","item":"https:\/\/lahehouse.com\/da\/produkter\/"},{"@type":"ListItem","position":3,"name":"Drivhus ML 1"}]},{"@type":"WebSite","@id":"https:\/\/lahehouse.com\/#website","url":"https:\/\/lahehouse.com\/","name":"L\u00e4he House","description":"Wooden greenhouses","publisher":{"@id":"https:\/\/lahehouse.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lahehouse.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"da-DK"},{"@type":"Organization","@id":"https:\/\/lahehouse.com\/#organization","name":"L\u00e4he House","url":"https:\/\/lahehouse.com\/","logo":{"@type":"ImageObject","inLanguage":"da-DK","@id":"https:\/\/lahehouse.com\/#\/schema\/logo\/image\/","url":"https:\/\/lahehouse.com\/wp-content\/uploads\/2022\/11\/Greenhouses-1.jpeg","contentUrl":"https:\/\/lahehouse.com\/wp-content\/uploads\/2022\/11\/Greenhouses-1.jpeg","width":1920,"height":1080,"caption":"L\u00e4he House"},"image":{"@id":"https:\/\/lahehouse.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lahehouse.com\/da\/wp-json\/wp\/v2\/pages\/24522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahehouse.com\/da\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lahehouse.com\/da\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lahehouse.com\/da\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lahehouse.com\/da\/wp-json\/wp\/v2\/comments?post=24522"}],"version-history":[{"count":30,"href":"https:\/\/lahehouse.com\/da\/wp-json\/wp\/v2\/pages\/24522\/revisions"}],"predecessor-version":[{"id":25169,"href":"https:\/\/lahehouse.com\/da\/wp-json\/wp\/v2\/pages\/24522\/revisions\/25169"}],"up":[{"embeddable":true,"href":"https:\/\/lahehouse.com\/da\/wp-json\/wp\/v2\/pages\/6487"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahehouse.com\/da\/wp-json\/wp\/v2\/media\/24524"}],"wp:attachment":[{"href":"https:\/\/lahehouse.com\/da\/wp-json\/wp\/v2\/media?parent=24522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}